{"id":10446,"date":"2020-11-12T12:12:58","date_gmt":"2020-11-12T12:12:58","guid":{"rendered":"https:\/\/tm.reventor.eu\/?post_type=konferenz&#038;p=10446"},"modified":"2026-05-27T07:37:45","modified_gmt":"2026-05-27T07:37:45","slug":"online-konferenz-2020","status":"publish","type":"konferenz","link":"https:\/\/trolleymotion.eu\/cs\/konferenz\/online-konferenz-2020\/","title":{"rendered":"Online Konferenz 2020"},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":""},"class_list":["post-10446","konferenz","type-konferenz","status-publish","format-standard","hentry"],"acf":{"hero_bereich":{"hero_badge":"Konferenzen","hero_title":"Virtual Conference 2020 \u2013 Elektrische Bussysteme trotz Pandemie im Wandel","hero_subtitle":"IMC, intelligente Energienetze und die Zukunft elektrischer Busnetze.","hero_date":"12.-13. November 2020 ","hero_location":"Online ","hero_primary_button_link":"","hero_secondary_button_link":null,"banner":false,"featured":false},"hero_bereich_source":{"label":"Hero","type":"group","formatted_value":{"hero_badge":"Konferenzen","hero_title":"Virtual Conference 2020 \u2013 Elektrische Bussysteme trotz Pandemie im Wandel","hero_subtitle":"IMC, intelligente Energienetze und die Zukunft elektrischer Busnetze.","hero_date":"12.-13. November 2020 ","hero_location":"Online ","hero_primary_button_link":"","hero_secondary_button_link":null,"banner":false,"featured":false}},"veranstaltungs_highlights":{"event_highlights":[{"icon":false,"title":"150 Teilnehmer ","description":"aus Verkehr, Industrie, Politik und Forschung"},{"icon":false,"title":"In-Motion-Charging","description":"Elektrische Busnetze mit Teiloberleitung"},{"icon":false,"title":"Smart Energy Systems","description":"Netzmanagement, Energiefl\u00fcsse und Digitalisierung"}]},"veranstaltungs_highlights_source":{"label":"Highlights\/Facts","type":"group","formatted_value":{"event_highlights":[{"icon":false,"title":"150 Teilnehmer ","description":"aus Verkehr, Industrie, Politik und Forschung"},{"icon":false,"title":"In-Motion-Charging","description":"Elektrische Busnetze mit Teiloberleitung"},{"icon":false,"title":"Smart Energy Systems","description":"Netzmanagement, Energiefl\u00fcsse und Digitalisierung"}]}},"strategische_themen":{"strategy_heading":"","descriptions":"Die urspr\u00fcnglich als Pr\u00e4senzveranstaltung geplante Konferenz musste 2020 aufgrund der COVID-19-Pandemie erstmals vollst\u00e4ndig online durchgef\u00fchrt werden. Trotzdem brachte die virtuelle Veranstaltung rund 150 internationale Teilnehmerinnen und Teilnehmer aus Verkehrsbetrieben, St\u00e4dten, Industrie, Forschung und europ\u00e4ischen Institutionen zusammen.\r\n\r\nIm Mittelpunkt stand das europ\u00e4ische Projekt \u201etrolley 2.0\u201c, das neue Ans\u00e4tze f\u00fcr batteriegest\u00fctzte Trolleybusse, In-Motion-Charging und intelligente Energienetze untersuchte. Pr\u00e4sentationen aus Solingen, Bergen, Landskrona und Z\u00fcrich zeigten, wie bestehende elektrische Infrastruktur f\u00fcr moderne elektrische Bussysteme weiterentwickelt werden kann \u2013 von Teiloberleitungen und Unterwerken bis zu digitalen Energie- und Netzmanagementsystemen. Erg\u00e4nzt wurde das Programm durch Beitr\u00e4ge der Europ\u00e4ischen Kommission und der UITP zu europ\u00e4ischen Strategien, der Clean Vehicles Directive und der Rolle emissionsfreier Bussysteme im \u00f6ffentlichen Verkehr.\r\n\r\n<strong>St\u00e4dte &amp; Systeme<\/strong>: Solingen, Bergen, Landskrona, Z\u00fcrich.","strategic_topics_image":false,"titel":"","strategy_subtitle":"","strategic_topics":""},"strategische_themen_source":{"label":"Einf\u00fchrung","type":"group","formatted_value":{"strategy_heading":"","descriptions":"<p>Die urspr\u00fcnglich als Pr\u00e4senzveranstaltung geplante Konferenz musste 2020 aufgrund der COVID-19-Pandemie erstmals vollst\u00e4ndig online durchgef\u00fchrt werden. Trotzdem brachte die virtuelle Veranstaltung rund 150 internationale Teilnehmerinnen und Teilnehmer aus Verkehrsbetrieben, St\u00e4dten, Industrie, Forschung und europ\u00e4ischen Institutionen zusammen.<\/p>\n<p>Im Mittelpunkt stand das europ\u00e4ische Projekt \u201etrolley 2.0\u201c, das neue Ans\u00e4tze f\u00fcr batteriegest\u00fctzte Trolleybusse, In-Motion-Charging und intelligente Energienetze untersuchte. Pr\u00e4sentationen aus Solingen, Bergen, Landskrona und Z\u00fcrich zeigten, wie bestehende elektrische Infrastruktur f\u00fcr moderne elektrische Bussysteme weiterentwickelt werden kann \u2013 von Teiloberleitungen und Unterwerken bis zu digitalen Energie- und Netzmanagementsystemen. Erg\u00e4nzt wurde das Programm durch Beitr\u00e4ge der Europ\u00e4ischen Kommission und der UITP zu europ\u00e4ischen Strategien, der Clean Vehicles Directive und der Rolle emissionsfreier Bussysteme im \u00f6ffentlichen Verkehr.<\/p>\n<p><strong>St\u00e4dte &amp; Systeme<\/strong>: Solingen, Bergen, Landskrona, Z\u00fcrich.<\/p>\n","strategic_topics_image":false,"titel":"","strategy_subtitle":"","strategic_topics":""}},"programmubersicht":{"program-title":"","program_button_text":"","program_button":"","program_days":[{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""},{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""},{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""}]},"programmubersicht_source":{"label":"Inhalte","type":"group","formatted_value":{"program-title":"","program_button_text":"","program_button":"","program_days":[{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""},{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""},{"program-icon":false,"day_date":"","day_title":"","day_subtitle":"","day_image":false,"program_details":""}]}},"sprecher":{"speaker-title":"","speaker_button_text":"","speaker_button_link":"","speakers":[{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""},{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""},{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""}]},"sprecher_source":{"label":"Sprecher","type":"group","formatted_value":{"speaker-title":"","speaker_button_text":"","speaker_button_link":"","speakers":[{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""},{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""},{"speaker_image":false,"speaker_name":"","speaker_position":"","speaker_company":"","speaker_description":""}]}},"veranstaltungsort":{"venue_name":"","venue_description":"","location_image":false},"veranstaltungsort_source":{"label":"Abschluss \/ Weitere Details","type":"group","formatted_value":{"venue_name":"","venue_description":"","location_image":false}},"partner_initiativen":{"partner_title":"","partner_button_text":"","partner_button":"","partners":null},"partner_initiativen_source":{"label":"Partner","type":"group","formatted_value":{"partner_title":"","partner_button_text":"","partner_button":"","partners":false}},"registrierung_teilnahme":{"registration_title":"","registration_description":"","registration_features":""},"registrierung_teilnahme_source":{"label":"Registrierung and Teilnahme","type":"group","formatted_value":{"registration_title":"","registration_description":"","registration_features":""}}},"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/konferenz\/10446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/konferenz"}],"about":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/types\/konferenz"}],"author":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":6,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/konferenz\/10446\/revisions"}],"predecessor-version":[{"id":11908,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/konferenz\/10446\/revisions\/11908"}],"wp:attachment":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/media?parent=10446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}