{"id":3397,"date":"2026-06-25T16:15:19","date_gmt":"2026-06-25T16:15:19","guid":{"rendered":"https:\/\/tm.reventor.eu\/?post_type=news&#038;p=3397"},"modified":"2026-07-01T09:45:17","modified_gmt":"2026-07-01T09:45:17","slug":"aufruf-zu-gebrauchten-bussen-fur-lviv","status":"publish","type":"news","link":"https:\/\/trolleymotion.eu\/cs\/news\/aufruf-zu-gebrauchten-bussen-fur-lviv\/","title":{"rendered":"Gebrauchte Busse f\u00fcr Lviv gesucht"},"content":{"rendered":"<p data-start=\"412\" data-end=\"689\"><strong data-start=\"412\" data-end=\"689\">Viele europ\u00e4ische St\u00e4dte erneuern derzeit ihre Busflotten. Gleichzeitig sucht Lviv nach gebrauchten Fahrzeugen, die weiterhin im \u00f6ffentlichen Verkehr eingesetzt werden k\u00f6nnen. trolley:motion unterst\u00fctzt den Austausch zwischen interessierten St\u00e4dten und Verkehrsunternehmen.<\/strong><\/p>\n<p data-start=\"691\" data-end=\"948\">Die Initiative wird im europ\u00e4ischen Netzwerk, unter anderem im Umfeld von Eurocities und der NetZero Cities Community, begleitet. Ziel ist es, einsatzf\u00e4higen Fahrzeugen eine zweite Nutzung zu erm\u00f6glichen und bestehende Ressourcen sinnvoll weiterzuverwerten.<\/p>\n<p data-start=\"950\" data-end=\"1005\"><strong data-start=\"950\" data-end=\"1005\">Gesucht werden St\u00e4dte und Verkehrsunternehmen, die:<\/strong><\/p>\n<ul data-start=\"1007\" data-end=\"1151\">\n<li data-section-id=\"1bu8ybs\" data-start=\"1007\" data-end=\"1055\">gebrauchte Busse zur Verf\u00fcgung stellen k\u00f6nnen,<\/li>\n<li data-section-id=\"xp2vrf\" data-start=\"1056\" data-end=\"1102\">einen Austausch mit Lviv pr\u00fcfen m\u00f6chten oder<\/li>\n<li data-section-id=\"1uvu9l7\" data-start=\"1103\" data-end=\"1151\">weitere Informationen zur Initiative w\u00fcnschen.<\/li>\n<\/ul>\n<p data-start=\"1153\" data-end=\"1319\">Interessierte Organisationen k\u00f6nnen sich direkt an trolley:motion wenden. Wir koordinieren die Anfragen und vermitteln den Kontakt zu den zust\u00e4ndigen Projektpartnern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele europ\u00e4ische St\u00e4dte erneuern derzeit ihre Busflotten. Gleichzeitig sucht Lviv nach gebrauchten Fahrzeugen, die weiterhin im \u00f6ffentlichen Verkehr eingesetzt werden k\u00f6nnen. trolley:motion unterst\u00fctzt den Austausch zwischen interessierten St\u00e4dten und Verkehrsunternehmen. Die Initiative wird im europ\u00e4ischen Netzwerk, unter anderem im Umfeld von Eurocities und der NetZero Cities Community, begleitet. Ziel ist es, einsatzf\u00e4higen Fahrzeugen eine zweite [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3388,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-3397","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/news\/3397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/comments?post=3397"}],"version-history":[{"count":6,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/news\/3397\/revisions"}],"predecessor-version":[{"id":11913,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/news\/3397\/revisions\/11913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/media\/3388"}],"wp:attachment":[{"href":"https:\/\/trolleymotion.eu\/cs\/wp-json\/wp\/v2\/media?parent=3397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}