{"id":20233,"date":"2026-07-10T17:03:43","date_gmt":"2026-07-10T15:03:43","guid":{"rendered":"https:\/\/tm.reventor.eu\/wissen\/anforderungen-zum-einsatz-von-elektrobussen-im-oeffentlichen-personennahverkehr\/"},"modified":"2026-07-10T17:03:43","modified_gmt":"2026-07-10T15:03:43","slug":"anforderungen-zum-einsatz-von-elektrobussen-im-oeffentlichen-personennahverkehr","status":"publish","type":"wissen","link":"https:\/\/trolleymotion.eu\/wissen\/anforderungen-zum-einsatz-von-elektrobussen-im-oeffentlichen-personennahverkehr\/","title":{"rendered":"Anforderungen zum Einsatz von Elektrobussen im \u00f6ffentlichen Personennahverkehr"},"content":{"rendered":"<p>Die Hamburger Hochbahn legt die Anforderungen an E-Busse vor der Hamburger Regelung von 2020 dar, dass nur noch emissionsfreie Busse beschafft werden d\u00fcrfen, und behandelt Flottenerfahrungen sowie die Innovationslinie 109.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","jahr":[780],"author-organization":[806],"thema":[638],"typ":[637],"class_list":["post-20233","wissen","type-wissen","status-publish","hentry","jahr-780","author-organization-gerhard-schenk-hamburger-hochbahn-ag","thema-konferenz","typ-presentation"],"acf":[],"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen\/20233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen"}],"about":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/types\/wissen"}],"author":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/media?parent=20233"}],"wp:term":[{"taxonomy":"jahr","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/jahr?post=20233"},{"taxonomy":"author-organization","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization?post=20233"},{"taxonomy":"thema","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/thema?post=20233"},{"taxonomy":"typ","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/typ?post=20233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}