{"id":20320,"date":"2026-07-10T17:03:47","date_gmt":"2026-07-10T15:03:47","guid":{"rendered":"https:\/\/tm.reventor.eu\/wissen\/energiereservestrategien-fuer-batteriebusse-mit-gelegenheitsladung\/"},"modified":"2026-07-10T17:03:47","modified_gmt":"2026-07-10T15:03:47","slug":"energiereservestrategien-fuer-batteriebusse-mit-gelegenheitsladung","status":"publish","type":"wissen","link":"https:\/\/trolleymotion.eu\/wissen\/energiereservestrategien-fuer-batteriebusse-mit-gelegenheitsladung\/","title":{"rendered":"Energiereservestrategien fuer Batteriebusse mit Gelegenheitsladung"},"content":{"rendered":"<p>Entwickelt Energiereservestrategien f\u00fcr Batteriebusse mit Gelegenheitsladung und kommt zu dem Schluss, dass die Robustheit gegen\u00fcber Versp\u00e4tungen von der Reservoirgr\u00f6\u00dfe abh\u00e4ngt und dass ein gr\u00f6\u00dferer Speicher einer h\u00f6heren Ladeleistung vorzuziehen ist.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","jahr":[852],"author-organization":[884],"thema":[638],"typ":[637],"class_list":["post-20320","wissen","type-wissen","status-publish","hentry","jahr-852","author-organization-thoralf-knote-fraunhofer-ivi","thema-konferenz","typ-presentation"],"acf":[],"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen\/20320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen"}],"about":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/types\/wissen"}],"author":[{"embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/media?parent=20320"}],"wp:term":[{"taxonomy":"jahr","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/jahr?post=20320"},{"taxonomy":"author-organization","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization?post=20320"},{"taxonomy":"thema","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/thema?post=20320"},{"taxonomy":"typ","embeddable":true,"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/typ?post=20320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}