{"id":915,"count":1,"description":"","link":"https:\/\/trolleymotion.eu\/author-organization\/fabio-monzali-technical-director-tper\/","name":"Fabio Monzali (Technical Director, TPER)","slug":"fabio-monzali-technical-director-tper","taxonomy":"author-organization","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization"}],"about":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/taxonomies\/author-organization"}],"wp:post_type":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen?author-organization=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}