{"id":708,"count":1,"description":"","link":"https:\/\/trolleymotion.eu\/author-organization\/walter-sennrich-vbl-ag-ralf-zabel-elbas-schweiz-ag\/","name":"Walter Sennrich (vbl AG); Ralf Zabel (ELBAS Schweiz AG)","slug":"walter-sennrich-vbl-ag-ralf-zabel-elbas-schweiz-ag","taxonomy":"author-organization","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization\/708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/author-organization"}],"about":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/taxonomies\/author-organization"}],"wp:post_type":[{"href":"https:\/\/trolleymotion.eu\/wp-json\/wp\/v2\/wissen?author-organization=708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}